{"id":133622,"date":"2026-05-13T04:38:55","date_gmt":"2026-05-13T01:38:55","guid":{"rendered":"https:\/\/www.argaliosdesign.com\/product\/teddy-%cf%83%ce%b1%ce%bb%ce%b9%ce%b1%cf%81%ce%b1-%ce%bc%ce%b9%ce%ba%cf%81%ce%b7-17%cf%8717\/"},"modified":"2026-05-13T04:38:57","modified_gmt":"2026-05-13T01:38:57","slug":"teddy-%cf%83%ce%b1%ce%bb%ce%b9%ce%b1%cf%81%ce%b1-%ce%bc%ce%b9%ce%ba%cf%81%ce%b7-17%cf%8717","status":"publish","type":"product","link":"https:\/\/www.argaliosdesign.com\/en\/product\/teddy-%cf%83%ce%b1%ce%bb%ce%b9%ce%b1%cf%81%ce%b1-%ce%bc%ce%b9%ce%ba%cf%81%ce%b7-17%cf%8717\/","title":{"rendered":"TEDDY \u03a3\u0391\u039b\u0399\u0391\u03a1\u0391 \u039c\u0399\u039a\u03a1\u0397 17\u03a717"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[3339],"product_tag":[],"class_list":{"0":"post-133622","1":"product","2":"type-product","3":"status-publish","5":"product_cat-emopeymata","6":"pa_-17-x-17","8":"first","9":"instock","10":"purchasable","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.argaliosdesign.com\/en\/wp-json\/wp\/v2\/product\/133622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.argaliosdesign.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.argaliosdesign.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.argaliosdesign.com\/en\/wp-json\/wp\/v2\/comments?post=133622"}],"wp:attachment":[{"href":"https:\/\/www.argaliosdesign.com\/en\/wp-json\/wp\/v2\/media?parent=133622"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.argaliosdesign.com\/en\/wp-json\/wp\/v2\/product_brand?post=133622"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.argaliosdesign.com\/en\/wp-json\/wp\/v2\/product_cat?post=133622"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.argaliosdesign.com\/en\/wp-json\/wp\/v2\/product_tag?post=133622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}