{"id":3923,"count":2,"description":"","link":"https:\/\/www.argaliosdesign.com\/en\/product-category\/argaliosdesign\/epoxiako\/xmas-2\/%ce%ba%ce%bf%cf%85%cf%81%cf%84%ce%b9%ce%bd%ce%b5%cf%83-%ce%bc%cf%80%ce%b1%ce%bd%ce%b9%ce%bf%cf%85\/","name":"\u039a\u039f\u03a5\u03a1\u03a4\u0399\u039d\u0395\u03a3 \u039c\u03a0\u0391\u039d\u0399\u039f\u03a5","slug":"%ce%ba%ce%bf%cf%85%cf%81%cf%84%ce%b9%ce%bd%ce%b5%cf%83-%ce%bc%cf%80%ce%b1%ce%bd%ce%b9%ce%bf%cf%85","taxonomy":"product_cat","parent":2845,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/www.argaliosdesign.com\/en\/wp-json\/wp\/v2\/product_cat\/3923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.argaliosdesign.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.argaliosdesign.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.argaliosdesign.com\/en\/wp-json\/wp\/v2\/product_cat\/2845"}],"wp:post_type":[{"href":"https:\/\/www.argaliosdesign.com\/en\/wp-json\/wp\/v2\/product?product_cat=3923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}